{"id":3698,"date":"2022-01-14T17:01:00","date_gmt":"2022-01-14T22:01:00","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=3698"},"modified":"2022-01-14T17:01:01","modified_gmt":"2022-01-14T22:01:01","slug":"le-port-de-shanghai-est-de-plus-en-plus-encombre-par-les-navires","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/shipping-congestion-is-growing-at-shanghai-port\/","title":{"rendered":"Le port de Shanghai est de plus en plus encombr\u00e9 par les navires"},"content":{"rendered":"<p>Les navires qui cherchent \u00e0 \u00e9viter les retards caus\u00e9s par le Covid en Chine se dirigent vers Shanghai, ce qui provoque une congestion croissante dans le plus grand port \u00e0 conteneurs du monde.<\/p>\n\n\n\n<p>Selon les transitaires et les experts, les entreprises de transport maritime font ce changement pour \u00e9viter les retards \u00e0 Ningbo, qui a suspendu certains services de camionnage pr\u00e8s de ce port apr\u00e8s l'apparition d'une \u00e9pid\u00e9mie de Covid-19. Les navires sont \u00e9galement redirig\u00e9s vers Xiamen, dans le sud, selon les donn\u00e9es maritimes de Bloomberg.<\/p>\n\n\n\n<p>Ces d\u00e9viations s'ajoutent \u00e0 la nouvelle vague de congestion des ports chinois, alors qu'un nombre croissant de villes sont confront\u00e9es \u00e0 des \u00e9pid\u00e9mies de virus. Les tests stricts auxquels sont soumis les travailleurs et les camionneurs avant les vacances du Nouvel An lunaire, \u00e0 la fin du mois, ne font qu'accentuer les tensions d\u00e9j\u00e0 existantes dans les cha\u00eenes d'approvisionnement, alors que la pand\u00e9mie entre dans sa troisi\u00e8me ann\u00e9e.<\/p>\n\n\n\n<p>Lire la suite : La Chine lutte contre le Covid : les lignes d'approvisionnement, la \" m\u00e8re de tous les chocs \".<\/p>\n\n\n\n<p>\u00c0 Shenzhen, centre technologique du pays, dans le sud, les tests effectu\u00e9s par les habitants et les camionneurs pour contenir une \u00e9pid\u00e9mie ont entra\u00een\u00e9 la formation d'une file d'attente de navires au port. Le terminal de Shekou a donc commenc\u00e9 \u00e0 restreindre l'acceptation des marchandises, ce qui signifie qu'\u00e0 partir de vendredi, les conteneurs pleins ne pourront \u00eatre achemin\u00e9s par camion que trois jours avant l'arriv\u00e9e des navires, a d\u00e9clar\u00e9 mardi l'op\u00e9rateur du terminal.<\/p>\n\n\n\n<p>Dans le m\u00eame temps, la ville de Tianjin, dans le nord de la Chine, a ordonn\u00e9 aux travailleurs de prendre une demi-journ\u00e9e de repos pour effectuer des tests sur le Covid, alors que les autorit\u00e9s tentent d'endiguer la propagation de la variante omicron. La capacit\u00e9 de camionnage est estim\u00e9e \u00e0 la moiti\u00e9 des niveaux normaux, et les chauffeurs doivent \u00eatre test\u00e9s quotidiennement avant d'entrer dans le port, a d\u00e9clar\u00e9 Alex Hersham, PDG du transitaire num\u00e9rique Zencargo.<\/p>\n\n\n\n<p>Cette \u00e9pid\u00e9mie s'est maintenant \u00e9tendue \u00e0 la ville portuaire de Dalian, deux personnes ayant voyag\u00e9 de Tianjin \u00e0 Dalian ayant \u00e9t\u00e9 confirm\u00e9es comme \u00e9tant atteintes de l'omicron.<\/p>\n\n\n\n<p>L'afflux de navires \u00e0 Shanghai a retard\u00e9 d'environ une semaine les horaires de d\u00e9part des porte-conteneurs, selon les transitaires. Ces retards risquent de se r\u00e9percuter sur les ports d\u00e9j\u00e0 satur\u00e9s des \u00c9tats-Unis et de l'Europe. Selon M. Hersham de Zencargo, les navires pourraient bient\u00f4t commencer \u00e0 \u00e9viter les ports chinois en raison du manque d'options.<\/p>\n\n\n\n<p>\"La question de la congestion portuaire continuera d'influer sur les cycles de r\u00e9approvisionnement ce trimestre, parall\u00e8lement \u00e0 la rupture de l'omicron et aux fermetures imminentes du Nouvel An chinois en Chine\", a d\u00e9clar\u00e9 Josh Brazil, vice-pr\u00e9sident de l'analyse de la cha\u00eene d'approvisionnement chez project44, une soci\u00e9t\u00e9 d'intelligence logistique.<\/p>","protected":false},"excerpt":{"rendered":"<p>Les navires cherchant \u00e0 \u00e9viter les retards caus\u00e9s par le Covid en Chine se dirigent vers Shanghai, provoquant une congestion croissante dans le plus grand port \u00e0 conteneurs du monde. Les entreprises de transport maritime font ce choix pour \u00e9viter les retards \u00e0 Ningbo, qui a suspendu certains services de camionnage \u00e0 proximit\u00e9 de ce port apr\u00e8s un accident de la route \u00e0 l'a\u00e9roport de Shanghai.<\/p>","protected":false},"author":1,"featured_media":3699,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/01\/Screen-Shot-2022-01-14-at-5.00.34-PM.png","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=3698"}],"version-history":[{"count":2,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3698\/revisions"}],"predecessor-version":[{"id":3702,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3698\/revisions\/3702"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3699"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=3698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=3698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=3698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}