{"id":3839,"date":"2022-03-25T11:47:34","date_gmt":"2022-03-25T16:47:34","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=3839"},"modified":"2022-03-25T11:47:36","modified_gmt":"2022-03-25T16:47:36","slug":"la-californie-met-les-taxes-sur-les-transporteurs-dd-dans-le-collimateur","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/california-is-putting-carrier-dd-charges-in-the-crosshairs\/","title":{"rendered":"La Californie met les frais de D&amp;D des transporteurs dans le collimateur"},"content":{"rendered":"<p><\/p>\n\n\n\n<p>Aux \u00c9tats-Unis, les vents contraires auxquels se heurtent les transporteurs maritimes sont de plus en plus forts.<\/p>\n\n\n\n<p>Alors qu'\u00e0 Washington, la r\u00e9forme de l'Ocean Shipping Reform Act vise l'immunit\u00e9 antitrust et appelle \u00e0 davantage de restrictions sur la capacit\u00e9 des transporteurs \u00e0 imposer des frais, les l\u00e9gislateurs californiens envisagent une l\u00e9gislation visant \u00e0 renforcer une loi qui limite les cas o\u00f9 des frais de d\u00e9tention et de surestaries (D&amp;D) peuvent \u00eatre pr\u00e9lev\u00e9s.<\/p>\n\n\n\n<p>Cette initiative juridique a re\u00e7u un large soutien de la part d'une coalition de groupes d'int\u00e9r\u00eat du secteur du camionnage et des propri\u00e9taires de cargaisons utiles.<\/p>\n\n\n\n<p>Le projet de loi propos\u00e9, AB 2406, interdirait ces frais lorsque les camionneurs ne peuvent pas prendre rendez-vous \u00e0 un terminal maritime ou lorsque les conteneurs d'un transporteur maritime ne peuvent pas \u00eatre renvoy\u00e9s \u00e0 un terminal.<\/p>\n\n\n\n<p>Elle limiterait \u00e9galement les taxes sur les conteneurs non pris en charge par un transporteur maritime parce qu'il contourne le port ou modifie son horaire.<\/p>","protected":false},"excerpt":{"rendered":"<p>Aux \u00c9tats-Unis, les vents contraires auxquels se heurtent les transporteurs maritimes sont de plus en plus forts. Alors que les pressions exerc\u00e9es \u00e0 Washington pour r\u00e9former l'Ocean Shipping Reform Act visent l'immunit\u00e9 antitrust et appellent \u00e0 une plus grande limitation de la capacit\u00e9 des transporteurs \u00e0 imposer des taxes, les l\u00e9gislateurs californiens, quant \u00e0 eux, s'efforcent d'am\u00e9liorer les conditions de travail des transporteurs et de r\u00e9duire les co\u00fbts.<\/p>","protected":false},"author":1,"featured_media":3573,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3839","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2021\/11\/211013134618-03-global-supply-chain-crisis-0920-exlarge-169.jpg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=3839"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3839\/revisions"}],"predecessor-version":[{"id":3840,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3839\/revisions\/3840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3573"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=3839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=3839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=3839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}