{"id":3897,"date":"2022-05-04T10:14:29","date_gmt":"2022-05-04T15:14:29","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=3897"},"modified":"2022-05-04T10:14:30","modified_gmt":"2022-05-04T15:14:30","slug":"les-maux-de-la-chaine-dapprovisionnement-mondiale-vont-sintensifier","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/global-supply-chain-headaches-poised-to-intensify\/","title":{"rendered":"Les maux de la cha\u00eene d'approvisionnement mondiale vont s'intensifier"},"content":{"rendered":"<p>LONDRES, 3 mai (Reuters) - Les probl\u00e8mes de la cha\u00eene d'approvisionnement mondiale semblent devoir s'aggraver, selon un nouveau rapport publi\u00e9 mardi, alors que les blocages du COVID-19 en Chine, l'invasion de l'Ukraine par la Russie et d'autres tensions entra\u00eenent des retards encore plus longs dans les ports et font grimper les co\u00fbts.En Chine, les navires en attente d'accostage au port de Shanghai sont actuellement au nombre de 344, soit une augmentation de 34% au cours du mois dernier, tandis que l'exp\u00e9dition d'un produit d'un entrep\u00f4t en Chine vers un entrep\u00f4t aux \u00c9tats-Unis prend actuellement 74 jours de plus que d'habitude.En Europe aussi, les navires en provenance de Chine arrivent en moyenne avec quatre jours de retard, ce qui entra\u00eene un certain nombre de r\u00e9percussions, notamment une p\u00e9nurie de conteneurs vides pour acheminer les marchandises fabriqu\u00e9es en Europe vers la c\u00f4te est des \u00c9tats-Unis. La congestion portuaire mondiale s'aggrave et devient de plus en plus r\u00e9pandue\", affirment Michael Tran, chef de la strat\u00e9gie de veille num\u00e9rique de RBC, et son coll\u00e8gue Jack Evans dans le rapport, reconnaissant qu'il est difficile de dire quand les choses s'am\u00e9lioreront.<br>Les navires et les conteneurs doivent \u00eatre disponibles au bon moment et au bon endroit pour \u00e9viter les annulations de r\u00e9servations. L'invasion de l'Ukraine par la Russie \u00e0 la fin du mois de f\u00e9vrier et le naufrage de plusieurs navires en mer Noire ont conduit les assureurs \u00e0 augmenter les primes de 11 \u00e0 51 points de pourcentage de la valeur du navire par rapport aux niveaux d'avant-guerre, qui \u00e9taient de 0,251 point de pourcentage.<br>Les prix du carburant marin \u00e0 Singapour, le plus grand port de ravitaillement au monde, ont quant \u00e0 eux bondi de 66% au cours de l'ann\u00e9e \u00e9coul\u00e9e. \"De nombreux acteurs du march\u00e9 pensaient que les cha\u00eenes d'approvisionnement seraient d\u00e9j\u00e0 d\u00e9m\u00eal\u00e9es, mais ce sc\u00e9nario ne s'est pas concr\u00e9tis\u00e9\", indique le rapport.Bien que les retards des navires se soient l\u00e9g\u00e8rement am\u00e9lior\u00e9s au cours des deux derniers mois, le d\u00e9lai moyen d'arriv\u00e9e d'un navire \u00e0 l'\u00e9chelle mondiale \u00e9tait encore de 7,26 jours en mars, un chiffre qui d\u00e9passe rarement 4,5 jours en temps normal, note RBC.Sur la c\u00f4te ouest des \u00c9tats-Unis, les ports de Los Angeles et de Long Beach continuent d'avoir du mal \u00e0 tenir la cadence. Une file d'attente de 19 navires \u00e0 Los Angeles et des inefficacit\u00e9s au niveau du port ont fait grimper le temps de rotation \u00e0 6,9 jours, contre 5 jours il y a un mois, bien qu'il soit encore inf\u00e9rieur au pic de 8.En Europe, ce que la Russie appelle une \"op\u00e9ration militaire sp\u00e9ciale\" en Ukraine a conduit plusieurs grandes compagnies maritimes \u00e0 suspendre le transport vers la mer Baltique et la mer Noire. Plusieurs pays europ\u00e9ens cl\u00e9s ont \u00e9galement interdit l'acc\u00e8s de leurs ports aux navires battant pavillon russe. Les temps de transport cumul\u00e9s pour les trois plus grands ports europ\u00e9ens de conteneurs, Rotterdam, Anvers et Hambourg, sont respectivement sup\u00e9rieurs de 81, 301 et 21% \u00e0 leurs niveaux normaux sur cinq ans. \"Une compression significative des temps de transport est n\u00e9cessaire avant que nous puissions sugg\u00e9rer en toute confiance une voie vers la normalisation des co\u00fbts de transport\", ont d\u00e9clar\u00e9 les analystes de RBC. \"Le probl\u00e8me ? Les choses empirent\".<\/p>","protected":false},"excerpt":{"rendered":"<p>LONDRES, 3 mai (Reuters) - Les probl\u00e8mes de la cha\u00eene d'approvisionnement mondiale semblent devoir s'aggraver, selon un nouveau rapport publi\u00e9 mardi, alors que les blocages du COVID-19 en Chine, l'invasion de l'Ukraine par la Russie et d'autres tensions entra\u00eenent des retards encore plus longs dans les ports et font grimper les co\u00fbts.L'\u00e9tude r\u00e9alis\u00e9e par des analystes<\/p>","protected":false},"author":1,"featured_media":3898,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3897","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/05\/NEW-Image.jpeg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=3897"}],"version-history":[{"count":2,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3897\/revisions"}],"predecessor-version":[{"id":3900,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3897\/revisions\/3900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3898"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=3897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=3897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=3897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}