{"id":3991,"date":"2022-06-23T11:09:44","date_gmt":"2022-06-23T16:09:44","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=3991"},"modified":"2022-06-23T11:09:53","modified_gmt":"2022-06-23T16:09:53","slug":"les-douanes-americaines-commencent-a-appliquer-la-loi-sur-la-protection-du-travail-force-des-ouighours","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/u-s-customs-begins-enforcing-uyghur-forced-labor-protection-act\/","title":{"rendered":"Les douanes am\u00e9ricaines commencent \u00e0 appliquer la loi sur la protection du travail forc\u00e9 des Ou\u00efghours"},"content":{"rendered":"<p>Cela va faire mal - Vos cha\u00eenes d'approvisionnement sont-elles pr\u00eates pour la loi sur le travail forc\u00e9 ?<\/p>\n\n\n\n<p>Pour les importateurs de produits chinois, le 21 juin est une date critique qui approche \u00e0 grands pas. Ce jour-l\u00e0, les douanes am\u00e9ricaines commenceront \u00e0 appliquer la loi sur l'importation et l'exportation des produits chinois.\u00a0<a href=\"https:\/\/www.cbp.gov\/trade\/forced-labor\/UFLPA?language_content_entity=en\">Loi sur la protection du travail forc\u00e9 des Ou\u00efghours<\/a>Les \u00c9tats-Unis ont adopt\u00e9 une nouvelle r\u00e9glementation interdisant toutes les importations en provenance de la province de Xinjiang, en Chine. Si les produits issus du travail forc\u00e9 ou p\u00e9nitentiaire sont interdits d'importation aux \u00c9tats-Unis depuis pr\u00e8s de 100 ans, cette nouvelle r\u00e9glementation est diff\u00e9rente.<\/p>\n\n\n\n<p>Avec ces nouvelles restrictions, les douanes am\u00e9ricaines pr\u00e9sumeront que tous les produits en provenance de la province du Xinjiang contiennent des substances dangereuses.&nbsp;<a href=\"https:\/\/www.state.gov\/forced-labor-in-chinas-xinjiang-region\/\">travail forc\u00e9&nbsp;<\/a>\u00e0 moins que vous ne puissiez prouver le contraire. Il s'agit d'une \"pr\u00e9somption r\u00e9futable\", dans laquelle vous \u00eates autoris\u00e9 \u00e0 pr\u00e9senter des documents et des arguments prouvant qu'aucun travail forc\u00e9 n'est inclus dans votre produit. Ce qui n'est pas clair, c'est la nature de cette documentation et la mani\u00e8re dont la d\u00e9cision sera prise par les douanes am\u00e9ricaines. En attendant, tous les envois de marchandises en provenance du Xinjiang ne pourront plus \u00eatre d\u00e9douan\u00e9s.<\/p>\n\n\n\n<p><strong>Autres lieux de travail ou\u00efghours<\/strong><\/p>\n\n\n\n<p>Ce qui est encore plus grave, c'est que les Ou\u00efghours sont connus pour \u00eatre transport\u00e9s par bus dans toute la Chine afin de travailler dans des usines en tant que main-d'\u0153uvre contractuelle. Les exp\u00e9ditions de produits provenant de ces usines seront \u00e9galement interdites jusqu'\u00e0 ce que l'importateur puisse prouver qu'il n'y a pas eu de travail forc\u00e9.  Bonne chance !<\/p>\n\n\n\n<p>Il appartiendra \u00e0 l'importateur de prouver qu'aucun travail forc\u00e9 n'a \u00e9t\u00e9 utilis\u00e9 dans l'une ou l'autre de ses cha\u00eenes d'approvisionnement. Bien que de nombreuses entreprises effectuent des audits des usines et de leurs pratiques de travail, on peut se demander s'il est possible d'identifier le travail forc\u00e9. L'usine dira-t-elle la v\u00e9rit\u00e9 sur son travail ? Qu'est-ce qui sera cach\u00e9 \u00e0 l'auditeur ?<\/p>\n\n\n\n<p><strong>Notifications de lettres<\/strong><\/p>\n\n\n\n<p>Certains importateurs ont d\u00e9j\u00e0 \u00e9t\u00e9 avertis par des lettres des douanes am\u00e9ricaines les informant des importations ant\u00e9rieures suspectes de travail forc\u00e9. Lors d'une r\u00e9cente conf\u00e9rence t\u00e9l\u00e9phonique avec les douanes am\u00e9ricaines, les agents charg\u00e9s de l'application de la loi ont d\u00e9clar\u00e9 que tous les importateurs soup\u00e7onn\u00e9s n'avaient pas re\u00e7u ces lettres pr\u00e9alables. Les douanes ont particuli\u00e8rement vis\u00e9 les importateurs de coton, de polysilicone, de produits \u00e0 base de tomate et de t\u00e9l\u00e9commandes de t\u00e9l\u00e9vision.<br>Les importateurs de v\u00eatements fabriqu\u00e9s dans d'autres r\u00e9gions de Chine, mais avec du coton cultiv\u00e9 et trait\u00e9 dans le Xinjiang, par exemple, peuvent constater que leurs envois seront \u00e9galement soumis \u00e0 la proc\u00e9dure de r\u00e9futation.<\/p>\n\n\n\n<p><strong>Que faire maintenant ?<\/strong><\/p>\n\n\n\n<p>Le contr\u00f4le du recours au travail forc\u00e9 dans vos cha\u00eenes d'approvisionnement exige un niveau d'examen tout \u00e0 fait nouveau. Il ne suffit pas d'auditer et de certifier vos usines et vos fournisseurs. La surveillance active doit \u00eatre un effort permanent, avec des examens approfondis des pratiques de travail.<\/p>\n\n\n\n<p>Les audits trimestriels des fournisseurs \u00e9taient suffisants, mais ce n'est plus le cas aujourd'hui. Les fournisseurs de niveau 1, de niveau 2 et de niveau 3 (voire plus) doivent faire l'objet d'un audit d\u00e9taill\u00e9 afin de d\u00e9couvrir les pi\u00e8ces et le contenu issus du travail forc\u00e9. Vous devez \u00eatre plus vigilant que jamais. Les responsables de la cha\u00eene d'approvisionnement doivent visiter les usines avec les auditeurs. Vous pouvez engager un auditeur de confiance en Chine pour visiter les usines fr\u00e9quemment, entre les audits trimestriels.<\/p>\n\n\n\n<p>Vous devriez commencer d\u00e8s maintenant \u00e0 documenter l'ensemble de votre cha\u00eene d'approvisionnement en Chine, en comprenant vos fournisseurs de niveau 1, de niveau 2, de niveau 3 et autres. Discutez de l'utilisation de la main-d'\u0153uvre ou\u00efgoure et demandez \u00e0 vos usines des d\u00e9clarations sous serment sign\u00e9es attestant qu'aucune main-d'\u0153uvre ou\u00efgoure n'est utilis\u00e9e pour la fabrication de leurs produits. Contr\u00f4lez souvent vos fournisseurs chinois, notamment en effectuant des visites inopin\u00e9es sur les cha\u00eenes de production. Entre deux audits en personne, engagez un auditeur ind\u00e9pendant situ\u00e9 en Chine pour compl\u00e9ter vos contr\u00f4les.<\/p>","protected":false},"excerpt":{"rendered":"<p>Cela va faire mal - Vos cha\u00eenes d'approvisionnement sont-elles pr\u00eates pour la loi sur le travail forc\u00e9 ? Pour les importateurs de produits chinois, le 21 juin est une date critique qui arrive \u00e0 grands pas. Ce jour-l\u00e0, les douanes am\u00e9ricaines commenceront \u00e0 appliquer la loi sur la protection du travail forc\u00e9 des Ou\u00efghours, interdisant toutes les importations de produits chinois.<\/p>","protected":false},"author":10,"featured_media":3992,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-3991","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/06\/US-Customs-and-Border-Protection-Department-of-Homeland-Security-Government-Agency-Sign.webp","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=3991"}],"version-history":[{"count":2,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3991\/revisions"}],"predecessor-version":[{"id":3996,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/3991\/revisions\/3996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3992"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=3991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=3991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=3991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}