{"id":4025,"date":"2022-07-06T14:29:37","date_gmt":"2022-07-06T19:29:37","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4025"},"modified":"2022-07-06T14:29:59","modified_gmt":"2022-07-06T19:29:59","slug":"le-port-de-halifax-fait-le-point-sur-les-defis-de-la-chaine-dapprovisionnement-2","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/port-of-halifax-update-on-supply-chain-challenges-2\/","title":{"rendered":"Le port d'Halifax fait le point sur les d\u00e9fis de la cha\u00eene d'approvisionnement"},"content":{"rendered":"<figure class=\"wp-block-table is-style-regular\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Nous savons que des clients subissent des retards dans le transport intermodal ferroviaire \u00e0 certaines rampes ferroviaires, comme le montre le rapport sur la dur\u00e9e moyenne de s\u00e9jour de cette semaine. Nous pouvons signaler que les navires continuent d'accoster \u00e0 l'arriv\u00e9e et de d\u00e9charger pour le d\u00e9part sans retard. Le transport par camion dans les terminaux reste fluide. Gr\u00e2ce aux r\u00e9centes mesures prises par le CN et PSA Halifax pour introduire un deuxi\u00e8me train quotidien et \u00e0 l'ajout d'\u00e9quipement de manutention terminale \u00e0 PSA Halifax Fairview Cove, nous fonctionnons avec fluidit\u00e9 \u00e0 toutes les rampes ferroviaires intermodales, \u00e0 l'exception de celle de Toronto. Les probl\u00e8mes de Toronto sont bien document\u00e9s au sein de l'industrie. L'Administration portuaire de Halifax, le CN et PSA Halifax continuent de travailler \u00e0 des solutions int\u00e9gr\u00e9es pour rationaliser les op\u00e9rations. Retards d'accostage des navires<br>En date du 6 juillet, les retards d'accostage des navires = 0Terminal Dwelle a consolid\u00e9 une vue d'ensemble sur 4 semaines des temps d'arr\u00eat des trains d'importation aux deux terminaux \u00e0 conteneurs d'Halifax. Pour une vue plus d\u00e9taill\u00e9e (y compris les tendances historiques par terminal individuel)\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/portofhalifax.us17.list-manage.com\/track\/click?u=56ce9cd85e9926afbf42efb72&amp;id=9b76367d99&amp;e=3c862ff277\" target=\"_blank\">cliquez ici<\/a>.<br><img decoding=\"async\" width=\"600\" src=\"https:\/\/ext.frontusercontent.com\/v1\/proxy\/C9ZqjcInt7kdwV-x7OKFH22Ic_YVm2toc2gortVkDDMmp4HyVTgWi_kGZObhyoaCa-cl3A5f45UmvJ6qHc-QosqbxDEzbGVZ31ZTv5c1StYv3f-MCwnVDTCJW1P0EKPGe_TTD_TNScWG-Jtnudc1AEJBTJ_Kpl6bsgGH-JQHaVsShWmTJuIYm_xzfkz08O69EjJuM4KXSZ7sXo8Sbbm6fChJRbJe2mYN5zoo0V4aXLfgsFTk#https:\/\/mcusercontent.com\/56ce9cd85e9926afbf42efb72\/images\/07dbff00-629c-cd52-8938-2f74af5d481e.png\" alt=\"\"><br><strong>S\u00e9jour \u00e0 quai r\u00e9el vs. planifi\u00e9<\/strong><br>Vue du nombre de porte-conteneurs qui terminent leur travail le long d'un poste d'amarrage \u00e0 Halifax par rapport \u00e0 la dur\u00e9e pr\u00e9vue de leur s\u00e9jour au poste d'amarrage.  Les navires qui terminent leur s\u00e9jour \u00e0 un poste d'amarrage dans la fen\u00eatre pr\u00e9vue indiquent l'efficacit\u00e9 des op\u00e9rations des navires partenaires du port.\u00a0<img decoding=\"async\" width=\"456\" src=\"https:\/\/ext.frontusercontent.com\/v1\/proxy\/M9O0LAAP8hqBL5jsY3p7R5dpIdi_9e4_HImyUkYpMiwW9q8rDuLENQyuBqV9cG3NUZsHZH9EquvXxCeLR0m1rXvIPYadaPFCYdjSVfricpXqSkEYIvWUF31YxVt6S0ABzL9-soiQfFIcft4PTL8aDHxtT1cgIpxAA6CT5PMy222jzi64pzcNbMns8nRy9sb6iCM6_QjcJ7oA9H6wQctJIrMfZBras9tBWu6-BF2trLGHz-bg#https:\/\/mcusercontent.com\/56ce9cd85e9926afbf42efb72\/images\/aa6e024c-2417-250e-755d-31b3ea7fc396.png\" alt=\"\"><strong>Temps de rotation des camions<\/strong><br>Une vue consolid\u00e9e sur 4 semaines des temps de service totaux des camions (attente \u00e0 la porte + rotation au terminal) aux deux terminaux \u00e0 conteneurs d'Halifax. Pour une vue plus d\u00e9taill\u00e9e (y compris les tendances historiques par terminal individuel)\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/portofhalifax.us17.list-manage.com\/track\/click?u=56ce9cd85e9926afbf42efb72&amp;id=20c65bda63&amp;e=3c862ff277\" target=\"_blank\">cliquez ici<\/a>.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><img decoding=\"async\" alt=\"\" src=\"https:\/\/ext.frontusercontent.com\/v1\/proxy\/sGPfpF7BMhmrtUZViiOmWNTLMCx9KOe02wW410mhYkSBma6ryuYKZXTMoXO0GN73PGf7JBRN_xVitLOaesiJgpz7yb7KeJ5PhlZ4YlGnFaqr6xDreJuEEJ1g4pFBPvkC3WeBkXE5cZLJLeoXz87jvD4PqfwgW9RhOpBQNQ8yJkq3XZ5mJ7msmubw9pIKsAnVvaJOcb7sqpOYocacnrWz6Qvq5e0Hi69egIO-mgYtOxaRGpUZ#https:\/\/mcusercontent.com\/56ce9cd85e9926afbf42efb72\/images\/e4b4597f-0e52-256a-b5a4-614c61874f79.png\" width=\"480\"><\/td><\/tr><\/tbody><\/table><\/figure>","protected":false},"excerpt":{"rendered":"<p>We are aware customers are experiencing rail intermodal transport delays to certain rail ramps as reflected in this week\u2019s average dwell report. We can report positively that vessels continue to dock upon arrival and un-dock for departure without delay. Terminal truck transport remains fluid. With<\/p>","protected":false},"author":10,"featured_media":3949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/06\/Port_of_Halifax_Logo.svg.png","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4025"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4025\/revisions"}],"predecessor-version":[{"id":4026,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4025\/revisions\/4026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3949"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}