{"id":4041,"date":"2022-07-13T08:17:50","date_gmt":"2022-07-13T13:17:50","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4041"},"modified":"2022-07-13T08:17:51","modified_gmt":"2022-07-13T13:17:51","slug":"les-incendies-de-foret-et-la-penurie-de-chassis-entrainent-une-nouvelle-augmentation-de-la-congestion-dans-les-ports-du-nam","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/forest-fires-and-chassis-shortage-see-nam-port-congestion-rise-again\/","title":{"rendered":"Les incendies de for\u00eat et la p\u00e9nurie de ch\u00e2ssis entra\u00eenent une nouvelle augmentation de la congestion du port de NAM"},"content":{"rendered":"<p>Les transporteurs maritimes mettent en garde contre l'aggravation de la congestion dans le port de Vancouver, sur la c\u00f4te ouest du Canada, tandis que les ports de la c\u00f4te est des \u00c9tats-Unis continuent d'\u00eatre submerg\u00e9s par les cartons d'importation.<\/p>\n\n\n\n<p>Le plus grand port de conteneurs du Canada conna\u00eet une vague de volumes d'importation record qui, combin\u00e9e aux retards intermodaux dus aux incendies de for\u00eat en Colombie-Britannique, a entra\u00een\u00e9 une forte augmentation des temps d'attente pour les importations de conteneurs.<\/p>\n\n\n\n<p>Hapag-Lloyd a d\u00e9clar\u00e9 que tous les navires faisant escale \u00e0 Vancouver \"continuent \u00e0 subir des retards importants\" et que les mouillages pour les navires en attente d'accostage \"restent pleins\".<\/p>\n\n\n\n<p>Entre-temps, Maersk a fait savoir que l'utilisation du chantier au terminal Centerm du port avait atteint un niveau improductif de 113%.<\/p>\n\n\n\n<p>\"Cela entra\u00eene des retards suppl\u00e9mentaires pour tous les volumes du terminal en raison de l'enfouissement des conteneurs\", a d\u00e9clar\u00e9 le transporteur.<\/p>\n\n\n\n<p>Elle a d\u00e9clar\u00e9 que la densit\u00e9 extr\u00eame des chantiers navals avait pour cons\u00e9quence que les navires \"passaient 50% de plus \u00e0 quai\".<\/p>\n\n\n\n<p>Maersk a d\u00e9clar\u00e9 qu'il \"travaillait\" avec l'installation g\u00e9r\u00e9e par DP World \"pour charger quotidiennement les conteneurs les plus longs\", mais les temps d'attente augmentent et les transporteurs sautent des escales et appliquent des suppl\u00e9ments pour congestion portuaire.<\/p>\n\n\n\n<p>\"Nous constatons des d\u00e9parts manqu\u00e9s sur nos services TP1 et TP9\", a d\u00e9clar\u00e9 Maersk, ajoutant que la congestion actuelle \"l'emp\u00eache d'envoyer davantage de chargeurs pour att\u00e9nuer la perte de capacit\u00e9\".<\/p>\n\n\n\n<p>Ailleurs, en Am\u00e9rique du Nord, les transporteurs continuent de mettre en garde contre une \"grave congestion\" dans les ports de la c\u00f4te est des \u00c9tats-Unis.<\/p>\n\n\n\n<p>Hapag-Lloyd a d\u00e9clar\u00e9 que les temps d'attente des navires \u00e0 New York \u00e9taient \"sup\u00e9rieurs \u00e0 20 jours\", tandis que le port de Savannah comptait 31 navires \u00e0 l'ancre en attente d'un poste d'amarrage la semaine derni\u00e8re.<\/p>\n\n\n\n<p>Dans les terminaux de New York, le transporteur a fait \u00e9tat d'une faible utilisation du chantier \u00e0 Maher (92%), alors qu'elle \u00e9tait plus g\u00e9rable au GCT Bayonne (75%) et \u00e0 l'APMT (72%).<\/p>\n\n\n\n<p>\"Tous les terminaux font \u00e9tat d'une utilisation \u00e9lev\u00e9e des postes d'amarrage et, dans certains cas, le d\u00e9chargement est mesur\u00e9 pour maintenir la fluidit\u00e9 du chantier\", a d\u00e9clar\u00e9 Hapag-Lloyd.<\/p>\n\n\n\n<p>\u00c0 quelques exceptions pr\u00e8s, les ports de la c\u00f4te est des \u00c9tats-Unis connaissent tous des temps d'attente prolong\u00e9s pour les navires, car les terminaux \u00e0 conteneurs font face \u00e0 la tendance au glissement c\u00f4tier de la c\u00f4te ouest, soutenue par les chargeurs qui r\u00e9acheminent les marchandises pour \u00e9viter toute retomb\u00e9e possible des n\u00e9gociations en cours sur le contrat de travail de la c\u00f4te ouest des \u00c9tats-Unis qui a expir\u00e9.<\/p>\n\n\n\n<p>De nombreux navires se dirigeant vers les ports de la c\u00f4te est en provenance d'Asie, via le canal de Panama ou le canal de Suez, re\u00e7oivent l'instruction de naviguer \u00e0 tr\u00e8s faible allure, mais sont alors souvent oblig\u00e9s de d\u00e9river pendant de longues p\u00e9riodes en dehors des mouillages d\u00e9j\u00e0 occup\u00e9s.<\/p>\n\n\n\n<p>En raison de la congestion sur la c\u00f4te atlantique, les temps d'attente pour les navires arrivant aux terminaux de Los Angeles et de Long Beach se sont consid\u00e9rablement r\u00e9duits et ne seraient plus que de trois ou quatre jours, alors qu'au d\u00e9but de l'ann\u00e9e, les temps d'attente \u00e9taient de 30 jours ou plus.<\/p>\n\n\n\n<p>En outre, la dur\u00e9e moyenne de s\u00e9jour des marchandises import\u00e9es dans les terminaux de Los Angeles est tomb\u00e9e \u00e0 4,4 jours, alors qu'elle atteignait 11 jours ou plus.<\/p>\n\n\n\n<p>Toutefois, le manque de disponibilit\u00e9 des ch\u00e2ssis est une pr\u00e9occupation constante dans les ports de la baie de San Pedro.<\/p>\n\n\n\n<p>\"La p\u00e9nurie de ch\u00e2ssis affecte tous les types de mouvements, des livraisons locales aux mouvements de terminaux vers\/depuis les rampes ferroviaires hors quai\", a d\u00e9clar\u00e9 Hapag-Lloyd.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ocean carriers are warning of worsening congestion at the Canadian west coast port of Vancouver, while US east coast ports continue to be overwhelmed with import boxes. Canada\u2019s biggest box port is experiencing a wave of record import volumes and when combined with intermodal delays<\/p>","protected":false},"author":10,"featured_media":4042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/07\/Is-there-a-Solution-to-the-U.S.-Chassis-Shortage-1-scaled-1.jpg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4041"}],"version-history":[{"count":2,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4041\/revisions"}],"predecessor-version":[{"id":4046,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4041\/revisions\/4046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/4042"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}