{"id":4064,"date":"2022-07-17T11:15:45","date_gmt":"2022-07-17T16:15:45","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4064"},"modified":"2022-07-17T11:15:48","modified_gmt":"2022-07-17T16:15:48","slug":"les-ports-sri-lankais-fonctionnent-normalement-malgre-les-troubles-politiques","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/sri-lankan-ports-operating-normally-despite-political-turmoil\/","title":{"rendered":"Les ports sri-lankais fonctionnent normalement malgr\u00e9 les troubles politiques"},"content":{"rendered":"<p>Au milieu des pires troubles politiques et \u00e9conomiques de l'histoire du pays, les op\u00e9rations portuaires autour de l'\u00eele de Sri Lanka parviennent \u00e0 se poursuivre normalement.<\/p>\n\n\n\n<p>Le pays est ruin\u00e9, n'ayant pas r\u00e9ussi \u00e0 rembourser les pr\u00eats internationaux, les approvisionnements en carburant sont limit\u00e9s et les pannes d'\u00e9lectricit\u00e9 sont d\u00e9sormais quotidiennes.<\/p>\n\n\n\n<p>La col\u00e8re face \u00e0 l'ineptie politique s'est r\u00e9pandue dans la capitale, Colombo, au cours du week-end, avec des milliers de manifestants qui ont pris d'assaut et occup\u00e9 les r\u00e9sidences du pr\u00e9sident et du premier ministre du pays.<\/p>\n\n\n\n<p>L'\u00eele est un point d'\u00e9tranglement g\u00e9opolitique et un centre de transbordement essentiel en Asie du Sud.<\/p>\n\n\n\n<p>L'agent portuaire GAC a pr\u00e9cis\u00e9 hier que malgr\u00e9 les perturbations et les manifestations en cours, l'activit\u00e9 portuaire, les services connexes et les autres services essentiels se poursuivent sans interruption.<\/p>\n\n\n\n<p>Un rapport publi\u00e9 en avril par l'institut indien de recherche sur les march\u00e9s CRISIL, filiale de S&amp;P Global, sugg\u00e8re que les compagnies maritimes pourraient chercher \u00e0 faire escale en Asie du Sud ailleurs qu'au Sri Lanka, en raison des p\u00e9nuries de carburant persistantes. Pendant la majeure partie de ce si\u00e8cle, le Sri Lanka a \u00e9t\u00e9 la premi\u00e8re plaque tournante de transbordement de la r\u00e9gion. Malgr\u00e9 de nombreuses sp\u00e9culations, principalement dans les cercles m\u00e9diatiques indiens, les responsables du port sri-lankais insistent sur le fait qu'il n'y a pas eu de baisse du trafic \u00e0 Colombo.<\/p>\n\n\n\n<p>Depuis le 1er juin, toutes les compagnies maritimes faisant escale dans le pays doivent payer leurs droits en dollars am\u00e9ricains et non plus dans la monnaie locale, qui a \u00e9t\u00e9 d\u00e9cim\u00e9e, ce qui, selon le gouvernement, devrait rapporter plus de $100 millions d'euros par an.<\/p>","protected":false},"excerpt":{"rendered":"<p>Au milieu des pires troubles politiques et \u00e9conomiques de l'histoire du pays, les op\u00e9rations portuaires autour de l'\u00eele de Sri Lanka parviennent \u00e0 se poursuivre normalement. Le pays est ruin\u00e9, n'ayant pas r\u00e9ussi \u00e0 rembourser les pr\u00eats internationaux, les approvisionnements en carburant sont limit\u00e9s et les coupures d'\u00e9lectricit\u00e9 sont d\u00e9sormais quotidiennes.<\/p>","protected":false},"author":10,"featured_media":4065,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/07\/Sri-Lanka-Ports-Authority-780x470-1.jpeg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4064"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4064\/revisions"}],"predecessor-version":[{"id":4066,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4064\/revisions\/4066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/4065"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}