{"id":4376,"date":"2023-02-22T10:18:46","date_gmt":"2023-02-22T15:18:46","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4376"},"modified":"2023-02-22T10:18:46","modified_gmt":"2023-02-22T15:18:46","slug":"des-conteneurs-transportant-des-importations-dune-valeur-de-plusieurs-milliards-de-dollars-sont-bloques-dans-les-ports-pakistanais","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/shipping-containers-with-billions-of-dollars-worth-of-imports-are-stuck-at-pakistans-ports\/","title":{"rendered":"Des conteneurs transportant des milliards de dollars d'importations sont bloqu\u00e9s dans les ports pakistanais"},"content":{"rendered":"<p>Plusieurs grandes entreprises pakistanaises ont interrompu leurs activit\u00e9s au cours des derniers mois, faute de mati\u00e8res premi\u00e8res ou de devises, voire des deux, aggravant ainsi les difficult\u00e9s d'une \u00e9conomie qui s'efforce d'\u00e9viter un d\u00e9faut de paiement.<\/p>\n\n\n\n<p>L'unit\u00e9 locale de Suzuki Motor Corp. a prolong\u00e9 la fermeture de son usine de fabrication jusqu'au 21 f\u00e9vrier, selon une d\u00e9claration \u00e0 la bourse vendredi, expliquant que les p\u00e9nuries de pi\u00e8ces persistent.<\/p>\n\n\n\n<p>Ghandhara Tyre &amp; Rubber Company, qui fabrique des pneus et des chambres \u00e0 air pour automobiles, a ferm\u00e9 son usine \u00e0 partir du 13 f\u00e9vrier, expliquant qu'elle \u00e9tait confront\u00e9e \u00e0 \"d'immenses obstacles pour importer des mati\u00e8res premi\u00e8res et obtenir le d\u00e9douanement des envois aupr\u00e8s des banques commerciales\".<\/p>\n\n\n\n<p>Il ne s'agit l\u00e0 que de deux entreprises parmi un groupe de soci\u00e9t\u00e9s cot\u00e9es en bourse, dont des fabricants d'engrais, d'acier et de textiles, qui ont ferm\u00e9 leurs usines pour une dur\u00e9e ind\u00e9termin\u00e9e ou suspendu leurs activit\u00e9s par intermittence, car elles sont confront\u00e9es \u00e0 une p\u00e9nurie de stocks ou de liquidit\u00e9s, voire \u00e0 une baisse de la demande.\u00a0<\/p>\n\n\n\n<p>Les $3,19 milliards de r\u00e9serves de devises \u00e9trang\u00e8res du Pakistan signifient que le pays n'est pas en mesure de financer les importations,\u00a0<a href=\"https:\/\/ratesearch.primefreight.com\/\">bloquer des milliers de conteneurs de fournitures dans ses ports et bloquer la production<\/a>L'inflation, qui est \u00e9galement la plus rapide depuis pr\u00e8s d'un demi-si\u00e8cle, met de nombreux biens hors de port\u00e9e des citoyens. L'inflation, qui n'a jamais \u00e9t\u00e9 aussi rapide depuis pr\u00e8s d'un demi-si\u00e8cle, met de nombreux biens hors de port\u00e9e du public.<\/p>\n\n\n\n<p>\"Ces fermetures auront un impact sur la croissance \u00e9conomique et augmenteront le taux de ch\u00f4mage dans le pays\", selon Tahir Abbas, responsable de la recherche et de l'investissement chez Arif Habib Limited, qui a d\u00e9clar\u00e9 n'avoir jamais vu une telle ampleur de fermetures parmi les entreprises cot\u00e9es en bourse.\u00a0<\/p>\n\n\n\n<p>\"La demande globale a diminu\u00e9 en raison de l'inflation qui dure depuis plusieurs d\u00e9cennies\", a d\u00e9clar\u00e9 M. Abbas. \"On assiste donc \u00e0 une destruction normale de la demande. En outre, nous prenons des mesures administratives pour ralentir l'\u00e9conomie\".<\/p>\n\n\n\n<p>\u00c0 l'instar de Suzuki, les unit\u00e9s locales de Honda Motor Co. et de Toyota Motor Corp. ont \u00e9galement subi des fermetures d'usines pendant plusieurs semaines. Ces fermetures ont pes\u00e9 sur l'\u00e9conomie pakistanaise.\u00a0<a href=\"https:\/\/www.primefreight.com\/fr\/\">ventes de voitures<\/a>\u00a0qui a chut\u00e9 de 65% pour atteindre son niveau le plus bas depuis pr\u00e8s de trois ans en janvier par rapport \u00e0 l'ann\u00e9e pr\u00e9c\u00e9dente, selon les donn\u00e9es de l'association des constructeurs automobiles du Pakistan (Pakistan Automotive Manufacturers Association).<\/p>\n\n\n\n<p>Les entreprises qui ont \u00e9galement ferm\u00e9 ou ralenti leurs activit\u00e9s sont l'unit\u00e9 pakistanaise de GSK Plc, Engro Fertilizers Limited, Fauji Fertilizer Bin Qasim Limited, Nishat Chunian Limited, Amreli Steels Limited, Millat Tractors Limited et Diamond Industries Limited.\u00a0<\/p>\n\n\n\n<p>\"La situation est devenue tr\u00e8s critique par rapport aux crises que nous avons connues en 2018 ou en 2008\", a d\u00e9clar\u00e9 M. Abbas, qui s'attend \u00e0 ce que la croissance \u00e9conomique ralentisse pour se situer dans une fourchette de 1%-1,25% au cours de l'exercice fiscal se terminant en juin, contre 6% l'ann\u00e9e derni\u00e8re.<\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>A bunch of Pakistan\u2019s biggest companies have halted operations in the past months as they ran out of raw materials or foreign exchange, or both, compounding the troubles of an economy that\u2019s trying to avert a debt default. The local unit of Suzuki Motor Corp.<\/p>","protected":false},"author":10,"featured_media":3292,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2020\/11\/container-rollover.jpg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4376"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4376\/revisions"}],"predecessor-version":[{"id":4377,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4376\/revisions\/4377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3292"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}