{"id":4378,"date":"2023-02-27T14:27:46","date_gmt":"2023-02-27T19:27:46","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4378"},"modified":"2023-02-27T14:27:59","modified_gmt":"2023-02-27T19:27:59","slug":"unifor-organise-des-votes-de-greve-a-la-cn","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/unifor-taking-strike-votes-at-cn\/","title":{"rendered":"Unifor organise des votes de gr\u00e8ve au CN"},"content":{"rendered":"<p>Les travailleurs d'Unifor au CN, notamment les m\u00e9caniciens et les \u00e9lectriciens de wagons de marchandises, n\u00e9gocient actuellement un nouveau contrat avec le CN, car leurs accords pr\u00e9c\u00e9dents ont expir\u00e9 le 31 d\u00e9cembre 2022. Unifor est un syndicat national qui repr\u00e9sente plus de 4 000 travailleurs du secteur des transports au Canada, y compris ceux qui travaillent pour le CN, Intermodal, CNTL et CN Savage Alberta Railway.<\/p>\n\n\n\n<p>Bien qu'il ait progress\u00e9 vers ses objectifs de n\u00e9gociation, Unifor a annonc\u00e9 qu'il restait quelques questions en suspens avec la section locale 100, notamment en ce qui concerne le processus actuel de d\u00e9pistage de substances dans le cadre de la politique de l'entreprise en mati\u00e8re de drogues et d'alcool. Unifor a d\u00e9pos\u00e9 un avis de diff\u00e9rend aupr\u00e8s du Service f\u00e9d\u00e9ral de m\u00e9diation et de conciliation (SFMC) et n\u00e9gocie depuis lors avec l'aide de conciliateurs f\u00e9d\u00e9raux.<\/p>\n\n\n\n<p>Le CN a offert des concessions qui comprennent des droits \u00e0 des vacances accumul\u00e9es et la suppression du consentement \u00e0 la retraite anticip\u00e9e (\u00e0 l'\u00e2ge de 55 ans). Cependant, le syndicat affirme que l'offre du CN n'est pas \u00e0 la hauteur des attentes de ses membres, en particulier \u00e0 la lumi\u00e8re de l'annonce r\u00e9cente par la soci\u00e9t\u00e9 de b\u00e9n\u00e9fices de $1,42 milliard au cours des trois derniers mois de l'ann\u00e9e 2022. En outre, la compagnie veut que les membres du Conseil 4000 renoncent au cong\u00e9 g\u00e9n\u00e9ral du 2 janvier, et il n'est pas certain que le CN continuera \u00e0 contribuer au Fonds de formation r\u00e9mun\u00e9r\u00e9 d'Unifor, qui assure l'\u00e9ducation et la formation des membres et des dirigeants locaux.<\/p>\n\n\n\n<p>\u00c0 mesure que les n\u00e9gociations se poursuivent, l'importance d'un transitaire fiable et efficace devient de plus en plus \u00e9vidente. Avec l'aide d'un transitaire, les entreprises peuvent s'assurer que leurs marchandises sont transport\u00e9es de mani\u00e8re efficace et efficiente, sans retards ou complications inutiles. Si vous cherchez un transitaire pour vous aider \u00e0 g\u00e9rer vos besoins en mati\u00e8re de transport, pensez \u00e0 Prime Freight, un fournisseur de confiance et exp\u00e9riment\u00e9 dans l'industrie. Contactez-nous d\u00e8s aujourd'hui pour en savoir plus sur nos services et sur la fa\u00e7on dont nous pouvons aider votre entreprise \u00e0 r\u00e9ussir. <\/p>","protected":false},"excerpt":{"rendered":"<p>Les travailleurs d'Unifor qui travaillent pour le CN, notamment les m\u00e9caniciens et les \u00e9lectriciens de wagons de marchandises, n\u00e9gocient actuellement un nouveau contrat avec le CN, car leurs accords pr\u00e9c\u00e9dents ont expir\u00e9 le 31 d\u00e9cembre 2022. Unifor est un syndicat national qui repr\u00e9sente plus de 4 000 travailleurs du secteur des transports au Canada, y compris ceux qui travaillent pour le CN,<\/p>","protected":false},"author":10,"featured_media":3973,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4378","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/06\/shutterstock_2005644545.jpg.optimal.jpg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4378"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4378\/revisions"}],"predecessor-version":[{"id":4379,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4378\/revisions\/4379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/3973"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}