{"id":4522,"date":"2023-07-20T16:00:38","date_gmt":"2023-07-20T21:00:38","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4522"},"modified":"2023-07-20T16:00:39","modified_gmt":"2023-07-20T21:00:39","slug":"avis-aux-clients-les-ports-de-colombie-britannique-reprennent-leurs-activites-normales","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/customer-advisory-british-columbia-ports-return-to-normal-operations\/","title":{"rendered":"Avis \u00e0 la client\u00e8le : les ports de la Colombie-Britannique reprennent leurs activit\u00e9s normales"},"content":{"rendered":"<p><strong>Introduction : <\/strong><\/p>\n\n\n\n<p>En date du 20 juillet 2023, nous avons le plaisir d'informer nos pr\u00e9cieux clients que la gr\u00e8ve qui affectait les ports de Vancouver et de Prince Rupert, en Colombie-Britannique, a \u00e9t\u00e9 r\u00e9solue. Le Syndicat international des d\u00e9bardeurs et magasiniers du Canada (ILWU Canada) a retir\u00e9 son pr\u00e9avis de gr\u00e8ve de 72 heures et les op\u00e9rations sont revenues \u00e0 la normale. Dans cet article, nous faisons le point sur l'\u00e9tat actuel des ports, le plan de redressement mis en place et les mesures prises pour r\u00e9sorber l'arri\u00e9r\u00e9 de marchandises.<\/p>\n\n\n\n<p><strong>Reprise des op\u00e9rations portuaires :<\/strong> <\/p>\n\n\n\n<p>Suite \u00e0 la r\u00e9tractation de l'avis de gr\u00e8ve, les travailleurs ont rapidement repris le travail et les op\u00e9rations de fret dans les ports de Vancouver et de Prince Rupert ont repris \u00e0 un niveau normal. Nous f\u00e9licitons ILWU Canada et la British Columbia Maritime Employers Association (BCMEA) d'\u00eatre parvenus \u00e0 un accord de principe, qui devra maintenant \u00eatre ratifi\u00e9 par les membres d'ILWU Canada avant d'\u00eatre finalis\u00e9.<\/p>\n\n\n\n<p><strong>Rem\u00e9dier \u00e0 l'arri\u00e9r\u00e9 des cargaisons :<\/strong><\/p>\n\n\n\n<p>Malgr\u00e9 la reprise des op\u00e9rations normales, il est essentiel de noter qu'un arri\u00e9r\u00e9 de fret existe toujours en raison des arr\u00eats de travail pendant le conflit social. Bien que des efforts aient \u00e9t\u00e9 faits pour traiter le fret accumul\u00e9, nous conseillons \u00e0 nos clients de s\u00e9curiser tout fret disponible d\u00e8s que possible. Ce faisant, nous pouvons assurer la bonne circulation des marchandises et minimiser les retards dans le traitement des cargaisons.<\/p>\n\n\n\n<p><strong>Plan de redressement du port :<\/strong> <\/p>\n\n\n\n<p>Le port de Vancouver met en \u0153uvre un plan de redressement complet afin de rationaliser les op\u00e9rations et d'acc\u00e9l\u00e9rer la r\u00e9sorption de l'arri\u00e9r\u00e9. Ce plan vise \u00e0 optimiser les processus de manutention des marchandises, \u00e0 am\u00e9liorer la coordination entre les diff\u00e9rentes parties prenantes et \u00e0 minimiser les perturbations potentielles \u00e0 l'avenir.<\/p>\n\n\n\n<p><strong>Calendrier des prochains ports :<\/strong> <\/p>\n\n\n\n<p>Afin de tenir nos clients bien inform\u00e9s, nous fournissons le calendrier actuel pour les ports de Prince Rupert et de Vancouver :<\/p>\n\n\n\n<p><strong>Prince Rupert :<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>MSC Utmost VIII voyage 324N - ETD 21 juillet<\/li><li>San Francisca voyage 326N - ETA 25 juillet<\/li><li>Maersk Santana voyage 327N - ETA 31 juillet<\/li><li>Maersk Sarnia voyage 328N - ETA 06 ao\u00fbt<\/li><\/ol>\n\n\n\n<p><strong>Vancouver :<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>MSC Abidjan voyage 323N - ETA 20 juillet<\/li><li>MSC Utmost VIII voyage 324N - ETA 27 juillet<\/li><li>San Francisca voyage 326N - ETA 01 ao\u00fbt<\/li><li>Maersk Santana voyage 327N - ETA 09 ao\u00fbt<\/li><li>Maersk Sarnia voyage 328N - ETA 16 ao\u00fbt<\/li><\/ol>\n\n\n\n<p><strong>Fraser Surrey :<\/strong><\/p>\n\n\n\n<ol class=\"wp-block-list\"><li>Cap Jervis voyage 321N - ETA 27 juillet<\/li><li>Seattle Express voyage 323N - 28 juillet<\/li><\/ol>\n\n\n\n<p><strong>Mise \u00e0 jour des op\u00e9rations ferroviaires :<\/strong> <\/p>\n\n\n\n<p>Nos partenaires ferroviaires, le CN et le CP, nous ont inform\u00e9s qu'ils poursuivaient leurs activit\u00e9s normalement. Ils travaillent activement \u00e0 l'\u00e9vacuation des cargaisons vieillissantes caus\u00e9es par les arr\u00eats de travail. Pour obtenir les derni\u00e8res informations sur les services ferroviaires, nous recommandons aux clients de contacter directement leurs fournisseurs de services ferroviaires respectifs.<\/p>\n\n\n\n<p><strong>Contr\u00f4le continu :<\/strong> <\/p>\n\n\n\n<p>Nous comprenons l'importance d'une communication transparente en ces temps difficiles et nous assurons \u00e0 nos clients que nous continuerons \u00e0 suivre la situation de pr\u00e8s. En cas de changement ou d'\u00e9volution, nous communiquerons rapidement des mises \u00e0 jour suppl\u00e9mentaires.<\/p>\n\n\n\n<p><strong>Conclusion :<\/strong> <\/p>\n\n\n\n<p>Avec le retour \u00e0 la normale des op\u00e9rations aux ports de Vancouver et de Prince Rupert, nous appr\u00e9cions la compr\u00e9hension et la coop\u00e9ration de nos pr\u00e9cieux clients tout au long du conflit de travail. Notre objectif premier est de rattraper le retard accumul\u00e9 dans le transport des marchandises et d'assurer une circulation fluide des marchandises. En collaborant avec l'ILWU Canada, la BCMEA et nos partenaires ferroviaires, nous sommes convaincus de pouvoir relever les d\u00e9fis et de continuer \u00e0 vous servir efficacement. Nous vous remercions de votre soutien continu et de la confiance que vous accordez \u00e0 nos services.<\/p>","protected":false},"excerpt":{"rendered":"<p>Introduction : En date du 20 juillet 2023, nous avons le plaisir d'informer nos pr\u00e9cieux clients que la gr\u00e8ve qui affectait les ports de Vancouver et de Prince Rupert en Colombie-Britannique a \u00e9t\u00e9 r\u00e9solue. Le Syndicat international des d\u00e9bardeurs et magasiniers du Canada (ILWU Canada) a r\u00e9tract\u00e9 sa d\u00e9cision de gr\u00e8ve.<\/p>","protected":false},"author":10,"featured_media":4506,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4522","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2023\/07\/20230713-194759-5-5500x3088ma-jpg.webp","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4522","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4522"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4522\/revisions"}],"predecessor-version":[{"id":4523,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4522\/revisions\/4523"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/4506"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4522"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4522"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4522"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}