{"id":4574,"date":"2023-07-31T13:57:56","date_gmt":"2023-07-31T18:57:56","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4574"},"modified":"2023-07-31T13:57:58","modified_gmt":"2023-07-31T18:57:58","slug":"mise-a-jour-des-negociations-entre-les-membres-de-la-bcmea-accord-de-principe-conclu-et-soumis-au-vote-de-ratification","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/bcmea-member-negotiations-update-tentative-agreement-reached-and-up-for-ratification-vote\/","title":{"rendered":"Mise \u00e0 jour des n\u00e9gociations avec les membres de la BCMEA : accord provisoire conclu et soumis au vote de ratification"},"content":{"rendered":"<p><strong>Introduction :<\/strong><\/p>\n\n\n\n<p>Dans le cadre d'une \u00e9volution importante du paysage syndical dans le secteur maritime de la Colombie-Britannique, l'International Longshore and Warehouse Union Canada (ILWU Canada) et la BC Maritime Employers Association (BCMEA) ont conclu avec succ\u00e8s des n\u00e9gociations avec l'aide du Conseil canadien des relations industrielles. Le r\u00e9sultat de ces n\u00e9gociations est une convention collective provisoire, qui doit maintenant \u00eatre soumise au vote de ratification des membres d'ILWU Canada cette semaine. Cet article donne un aper\u00e7u du processus de n\u00e9gociation, de l'accord propos\u00e9 et du calendrier pr\u00e9vu pour le vote de ratification.<\/p>\n\n\n\n<p><strong>Processus de ratification :<\/strong><\/p>\n\n\n\n<p>L'accord de principe n\u00e9goci\u00e9 doit maintenant faire l'objet d'un vote de ratification parmi les membres de l'ILWU Canada. Le mercredi 2 ao\u00fbt, toutes les sections locales tiendront une r\u00e9union d'arr\u00eat de travail \u00e0 8 h. Le processus de vote devrait ensuite avoir lieu le jeudi 3 ao\u00fbt et le vendredi 4 ao\u00fbt. Le processus de vote devrait ensuite se d\u00e9rouler le jeudi 3 ao\u00fbt et le vendredi 4 ao\u00fbt. Le r\u00e9sultat du vote sera communiqu\u00e9 \u00e0 l'issue de ces s\u00e9ances de vote. Il est important de noter que le vote de ratification joue un r\u00f4le essentiel dans la d\u00e9termination de l'acceptation et de l'entr\u00e9e en vigueur de la convention collective propos\u00e9e.<\/p>\n\n\n\n<p><strong>Mises \u00e0 jour continues :<\/strong><\/p>\n\n\n\n<p>Au fur et \u00e0 mesure du d\u00e9roulement de ce processus crucial, l'ILWU Canada et la BCMEA continueront \u00e0 fournir des mises \u00e0 jour \u00e0 leurs parties prenantes respectives et au public. Les parties concern\u00e9es reconnaissent l'importance de l'accord et comprennent l'importance de tenir toutes les parties int\u00e9ress\u00e9es inform\u00e9es des progr\u00e8s et des d\u00e9veloppements. Les parties prenantes peuvent s'attendre \u00e0 recevoir d'autres mises \u00e0 jour, le cas \u00e9ch\u00e9ant, afin de garantir la transparence et la responsabilit\u00e9 tout au long du processus de ratification.<\/p>\n\n\n\n<p><strong>Conclusion :<\/strong><\/p>\n\n\n\n<p>L'accord de principe n\u00e9goci\u00e9 entre ILWU Canada et BCMEA marque une \u00e9tape importante dans le paysage syndical maritime de la Colombie-Britannique. L'effort de collaboration et l'implication du Conseil canadien des relations industrielles illustrent l'engagement \u00e0 parvenir \u00e0 une r\u00e9solution \u00e9quitable et mutuellement b\u00e9n\u00e9fique. L'accord propos\u00e9 devant maintenant faire l'objet d'un vote de ratification, les membres d'ILWU Canada et les employeurs membres ont un r\u00f4le essentiel \u00e0 jouer pour d\u00e9terminer le r\u00e9sultat final. Au fur et \u00e0 mesure que le processus de vote progresse, toutes les parties prenantes suivront de pr\u00e8s les mises \u00e0 jour afin de comprendre les implications et l'impact potentiel sur l'industrie maritime dans la r\u00e9gion.<\/p>","protected":false},"excerpt":{"rendered":"<p>Introduction : Les n\u00e9gociations entre l'International Longshore and Warehouse Union Canada (ILWU Canada) et la BC Maritime Employers Association (BCMEA), avec l'aide du Conseil canadien des relations industrielles, ont \u00e9t\u00e9 couronn\u00e9es de succ\u00e8s, ce qui constitue un d\u00e9veloppement important pour le paysage syndical du secteur maritime de la Colombie-Britannique. Le Conseil canadien des relations industrielles (CCRI) a aid\u00e9 l'ILWU Canada \u00e0 conclure les n\u00e9gociations.<\/p>","protected":false},"author":10,"featured_media":4507,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4574","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2023\/07\/Screenshot-2023-07-14-at-9.53.34\u202fAM.png","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4574"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4574\/revisions"}],"predecessor-version":[{"id":4575,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4574\/revisions\/4575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/4507"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4574"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4574"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}