{"id":4652,"date":"2023-10-20T15:32:31","date_gmt":"2023-10-20T20:32:31","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4652"},"modified":"2023-10-20T15:32:33","modified_gmt":"2023-10-20T20:32:33","slug":"unifor-signifie-a-la-corporation-de-gestion-de-la-voie-maritime-du-saint-laurent-un-avis-de-greve-de-72-heures","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/unifor-serves-the-st-lawrence-seaway-management-corporation-with-a-72-hour-strike-notice\/","title":{"rendered":"UNIFOR signifie \u00e0 la Corporation de gestion de la Voie maritime du Saint-Laurent un pr\u00e9avis de gr\u00e8ve de 72 heures"},"content":{"rendered":"<p>La Corporation de Gestion de la Voie Maritime du Saint-Laurent (CGVMSL) a re\u00e7u un avis de gr\u00e8ve de 72 heures de la part d'UNIFOR le 18 octobre 2023, affectant les sections locales 4211, 4319, 4212, 4323 et 4320. Le syndicat a indiqu\u00e9 son intention de commencer la gr\u00e8ve \u00e0 00h01 le dimanche 22 octobre 2023.<\/p>\n\n\n\n<p>La Voie maritime du Saint-Laurent joue un r\u00f4le essentiel dans l'\u00e9conomie nord-am\u00e9ricaine et sa cha\u00eene d'approvisionnement. Cette action syndicale, en particulier \u00e0 un moment o\u00f9 la demande mondiale de c\u00e9r\u00e9ales est pressante et o\u00f9 l'offre a \u00e9t\u00e9 affect\u00e9e par divers facteurs, notamment la situation en Ukraine et la multiplication des ph\u00e9nom\u00e8nes m\u00e9t\u00e9orologiques extr\u00eames dans le monde entier, risque d'avoir des cons\u00e9quences consid\u00e9rables.<\/p>\n\n\n\n<p>Malgr\u00e9 le pr\u00e9avis de gr\u00e8ve, la CGVMSL reste d\u00e9termin\u00e9e \u00e0 trouver une solution \u00e9quitable. La corporation continuera \u00e0 n\u00e9gocier s\u00e9rieusement avec l'aide d'un m\u00e9diateur nomm\u00e9 par le gouvernement f\u00e9d\u00e9ral. UNIFOR est l'organisme qui repr\u00e9sente les 361 employ\u00e9s syndiqu\u00e9s de la Voie maritime.<\/p>\n\n\n\n<p>\u00c0 la lumi\u00e8re de l'avis de gr\u00e8ve d'UNIFOR, la CGVMSL a rapidement entrepris l'ex\u00e9cution de plans d\u00e9taill\u00e9s pour assurer une fermeture m\u00e9thodique et s\u00e9curitaire du syst\u00e8me dans la p\u00e9riode stipul\u00e9e de 72 heures. Si les travailleurs syndiqu\u00e9s poursuivent leur mouvement de gr\u00e8ve, la Voie maritime du Saint-Laurent sera inaccessible \u00e0 tout le trafic.<\/p>\n\n\n\n<p>Pour de plus amples informations sur la Voie maritime et ses op\u00e9rations, veuillez consulter le site suivant <a href=\"http:\/\/www.greatlakes-seaway.com\/\">www.greatlakes-seaway.com<\/a>.<\/p>","protected":false},"excerpt":{"rendered":"<p>La Corporation de Gestion de la Voie Maritime du Saint-Laurent (CGVMSL) a re\u00e7u un avis de gr\u00e8ve de 72 heures de la part d'UNIFOR pour le 18 octobre 2023, affectant les sections locales 4211, 4319, 4212, 4323 et 4320. Le syndicat a indiqu\u00e9 son intention de commencer la gr\u00e8ve \u00e0 00h01 le dimanche 18 octobre.<\/p>","protected":false},"author":10,"featured_media":4104,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2022\/08\/106858897-1616612168697-2019-11-17T190504Z_990002758_RC27DD9F8LEZ_RTRMADP_3_EGYPT-SUEZCANAL-ANNIVERSARY-scaled.jpeg","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4652"}],"version-history":[{"count":1,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4652\/revisions"}],"predecessor-version":[{"id":4653,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4652\/revisions\/4653"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/4104"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}