{"id":4740,"date":"2024-01-04T12:34:07","date_gmt":"2024-01-04T17:34:07","guid":{"rendered":"https:\/\/www.primefreight.com\/?p=4740"},"modified":"2024-01-04T12:39:27","modified_gmt":"2024-01-04T17:39:27","slug":"augmentation-generale-de-la-duree-de-sejour-sur-la-cote-ouest","status":"publish","type":"post","link":"https:\/\/www.primefreight.com\/fr\/west-coast-general-increase-in-dwell-times\/","title":{"rendered":"C\u00f4te Ouest : Augmentation g\u00e9n\u00e9rale des dur\u00e9es de s\u00e9jour"},"content":{"rendered":"<p><br>R\u00e9cemment, les terminaux de la c\u00f4te ouest ont connu une augmentation notable de la dur\u00e9e d'immobilisation, ce qui a nui \u00e0 l'efficacit\u00e9 du flux de marchandises. Cette augmentation est li\u00e9e \u00e0 divers facteurs, les d\u00e9routements du canal de Suez \u00e9tant l'un des principaux. Le temps d'attente, c'est-\u00e0-dire la dur\u00e9e pendant laquelle les conteneurs restent dans les terminaux, a augment\u00e9 sur la c\u00f4te ouest, ce qui a eu un impact sur l'ensemble de la cha\u00eene logistique et a entra\u00een\u00e9 des retards pour les fabricants, les distributeurs et les d\u00e9taillants.<\/p>\n\n\n\n<p>Le canal de Suez, une voie maritime vitale, a historiquement reli\u00e9 l'Orient et l'Occident. Les perturbations et les changements d'itin\u00e9raires ont redirig\u00e9 un volume important de trafic maritime vers les terminaux de la c\u00f4te ouest, mettant \u00e0 rude \u00e9preuve leur capacit\u00e9 et provoquant des encombrements. Cet afflux a entra\u00een\u00e9 une augmentation de la dur\u00e9e d'immobilisation des navires qui ont opt\u00e9 pour des itin\u00e9raires plus longs, ce qui a affect\u00e9 la synchronisation de la manutention des marchandises. Actuellement, comme le montre le tableau ci-dessus, le temps de s\u00e9jour moyen sur la c\u00f4te ouest est d'un peu moins de 10 jours, le Centerm ayant la moyenne la plus \u00e9lev\u00e9e avec 15 jours.<\/p>","protected":false},"excerpt":{"rendered":"<p>R\u00e9cemment, les terminaux de la c\u00f4te ouest ont connu une augmentation notable de la dur\u00e9e d'immobilisation, ce qui a nui \u00e0 l'efficacit\u00e9 du flux de marchandises. Cette augmentation est li\u00e9e \u00e0 divers facteurs, les d\u00e9routements du canal de Suez \u00e9tant l'un des principaux. Le temps d'attente, c'est-\u00e0-dire la dur\u00e9e pendant laquelle les conteneurs passent dans les terminaux, a augment\u00e9 dans tous les pays de l'Union europ\u00e9enne.<\/p>","protected":false},"author":1,"featured_media":4745,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","_mbp_gutenberg_autopost":false,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-4740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"jetpack_featured_media_url":"https:\/\/www.primefreight.com\/wp-content\/uploads\/2024\/01\/image001.png","_links":{"self":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/comments?post=4740"}],"version-history":[{"count":3,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4740\/revisions"}],"predecessor-version":[{"id":4748,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/posts\/4740\/revisions\/4748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media\/4745"}],"wp:attachment":[{"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/media?parent=4740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/categories?post=4740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.primefreight.com\/fr\/wp-json\/wp\/v2\/tags?post=4740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}